{"id":217147,"date":"2020-09-20T05:06:14","date_gmt":"2020-09-20T05:06:14","guid":{"rendered":"https:\/\/urdu.app.com.pk\/urdu\/?p=217147"},"modified":"2020-09-20T19:06:33","modified_gmt":"2020-09-20T19:06:33","slug":"%d8%a7%d9%be%d9%88%d8%b2%db%8c%d8%b4%d9%86-%da%a9%db%8c-%da%af%d9%be-%d8%b4%d9%be-%da%a9%db%8c-%d9%85%d8%ad%d9%81%d9%84-%d9%85%db%8c%da%ba-%d8%b2%db%8c%d8%a7%d8%af%db%81-%d8%aa%d8%b1-%d9%88%db%81","status":"publish","type":"post","link":"https:\/\/urdu.app.com.pk\/urdu\/%d8%a7%d9%be%d9%88%d8%b2%db%8c%d8%b4%d9%86-%da%a9%db%8c-%da%af%d9%be-%d8%b4%d9%be-%da%a9%db%8c-%d9%85%d8%ad%d9%81%d9%84-%d9%85%db%8c%da%ba-%d8%b2%db%8c%d8%a7%d8%af%db%81-%d8%aa%d8%b1-%d9%88%db%81\/","title":{"rendered":"\u0627\u067e\u0648\u0632\u06cc\u0634\u0646 \u06a9\u06cc \u06af\u067e \u0634\u067e \u06a9\u06cc \u0645\u062d\u0641\u0644 \u0645\u06cc\u06ba \u0632\u06cc\u0627\u062f\u06c1 \u062a\u0631 \u0648\u06c1\u06cc \u0644\u0648\u06af \u0628\u0648\u0644\u06d2 \u062c\u0646 \u06a9\u06d2 \u0646\u0627\u0645 \u06a9\u06d2 \u0622\u062e\u0631 \u0645\u06cc\u06ba \u201d\u0634\u0631\u06cc\u0641\u201c \u06cc\u0627 \u201d\u0632\u0631\u062f\u0627\u0631\u06cc\u201c \u0644\u06af\u062a\u0627 \u06c1\u06d2\u060c \u0628\u0627\u0642\u06cc \u0627\u06cc\u06a9 \u062f\u0648 \u06a9\u06cc \u0622\u0648\u0627\u0632 \u062e\u0648\u062f \u06c1\u06cc \u0628\u0646\u062f \u06a9\u0631 \u062f\u06cc \u06af\u0626\u06cc\u06d4\u0648\u0641\u0627\u0642\u06cc \u0648\u0632\u06cc\u0631 \u062d\u0645\u0627\u062f \u0627\u0638\u06c1\u0631"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div><p>\u0627\u0633\u0644\u0627\u0645 \u0622\u0628\u0627\u062f \u06d4 20 \u0633\u062a\u0645\u0628\u0631 (\u0627\u06d2 \u067e\u06cc \u067e\u06cc) \u0648\u0641\u0627\u0642\u06cc \u0648\u0632\u06cc\u0631 \u0635\u0646\u0639\u062a \u0648 \u067e\u06cc\u062f\u0627\u0648\u0627\u0631 \u062d\u0645\u0627\u062f \u0627\u0638\u06c1\u0631 \u0646\u06d2 \u06a9\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u067e\u0648\u0632\u06cc\u0634\u0646 \u06a9\u06cc \u06af\u067e \u0634\u067e \u06a9\u06cc \u0645\u062d\u0641\u0644 \u0645\u06cc\u06ba \u0632\u06cc\u0627\u062f\u06c1 \u062a\u0631 \u0648\u06c1\u06cc \u0644\u0648\u06af \u0628\u0648\u0644\u06d2 \u062c\u0646 \u06a9\u06d2 \u0646\u0627\u0645 \u06a9\u06d2 \u0622\u062e\u0631 \u0645\u06cc\u06ba \u201d\u0634\u0631\u06cc\u0641\u201c \u06cc\u0627 \u201d\u0632\u0631\u062f\u0627\u0631\u06cc\u201c \u0644\u06af\u062a\u0627 \u06c1\u06d2\u060c \u0628\u0627\u0642\u06cc \u0627\u06cc\u06a9 \u062f\u0648 \u06a9\u06cc \u0622\u0648\u0627\u0632 \u062e\u0648\u062f \u06c1\u06cc \u0628\u0646\u062f \u06a9\u0631 \u062f\u06cc \u06af\u0626\u06cc\u06d4 \u062d\u0645\u0627\u062f \u0627\u0638\u06c1\u0631 \u0646\u06d2 \u0633\u0645\u0627\u062c\u06cc \u0631\u0627\u0628\u0637\u06d2 \u06a9\u06cc \u0648\u06cc\u0628 \u0633\u0627\u0626\u0679 \u0679\u0648\u0626\u0679\u0631 \u067e\u0631 \u0627\u067e\u0646\u06d2 \u0627\u06cc\u06a9 \u0679\u0648\u06cc\u0679 \u0645\u06cc\u06ba \u06a9\u06c1\u0627 \u06a9\u06c1 \u06af\u067e \u0634\u067e \u06a9\u06cc \u0645\u062d\u0641\u0644 \u0645\u06cc\u06ba \u0634\u0631\u06cc\u06a9 \u0644\u0648\u06af\u0648\u06ba \u06a9\u06cc \u062c\u0645\u06c1\u0648\u0631\u06cc\u062a \u0627\u062a\u0646\u06cc \u0633\u06cc \u06c1\u06cc \u06c1\u06d2\u06d4<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0627\u0633\u0644\u0627\u0645 \u0622\u0628\u0627\u062f \u06d4 20 \u0633\u062a\u0645\u0628\u0631 (\u0627\u06d2 \u067e\u06cc \u067e\u06cc) \u0648\u0641\u0627\u0642\u06cc \u0648\u0632\u06cc\u0631 \u0635\u0646\u0639\u062a \u0648 \u067e\u06cc\u062f\u0627\u0648\u0627\u0631 \u062d\u0645\u0627\u062f \u0627\u0638\u06c1\u0631 \u0646\u06d2 \u06a9\u06c1\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0627\u067e\u0648\u0632\u06cc\u0634\u0646 \u06a9\u06cc \u06af\u067e \u0634\u067e \u06a9\u06cc \u0645\u062d\u0641\u0644 \u0645\u06cc\u06ba \u0632\u06cc\u0627\u062f\u06c1 \u062a\u0631 \u0648\u06c1\u06cc \u0644\u0648\u06af \u0628\u0648\u0644\u06d2 \u062c\u0646 \u06a9\u06d2 \u0646\u0627\u0645 \u06a9\u06d2 \u0622\u062e\u0631 \u0645\u06cc\u06ba \u201d\u0634\u0631\u06cc\u0641\u201c \u06cc\u0627 \u201d\u0632\u0631\u062f\u0627\u0631\u06cc\u201c \u0644\u06af\u062a\u0627 \u06c1\u06d2\u060c \u0628\u0627\u0642\u06cc \u0627\u06cc\u06a9 \u062f\u0648 \u06a9\u06cc \u0622\u0648\u0627\u0632 \u062e\u0648\u062f \u06c1\u06cc \u0628\u0646\u062f \u06a9\u0631 \u062f\u06cc \u06af\u0626\u06cc\u06d4 \u062d\u0645\u0627\u062f \u0627\u0638\u06c1\u0631&#8230;<\/p>\n","protected":false},"author":3,"featured_media":196653,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"post_template":[],"top_category":[],"class_list":["post-217147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-national"],"acf":[],"_links":{"self":[{"href":"https:\/\/urdu.app.com.pk\/urdu\/wp-json\/wp\/v2\/posts\/217147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urdu.app.com.pk\/urdu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urdu.app.com.pk\/urdu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urdu.app.com.pk\/urdu\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/urdu.app.com.pk\/urdu\/wp-json\/wp\/v2\/comments?post=217147"}],"version-history":[{"count":0,"href":"https:\/\/urdu.app.com.pk\/urdu\/wp-json\/wp\/v2\/posts\/217147\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urdu.app.com.pk\/urdu\/wp-json\/wp\/v2\/media\/196653"}],"wp:attachment":[{"href":"https:\/\/urdu.app.com.pk\/urdu\/wp-json\/wp\/v2\/media?parent=217147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urdu.app.com.pk\/urdu\/wp-json\/wp\/v2\/categories?post=217147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urdu.app.com.pk\/urdu\/wp-json\/wp\/v2\/tags?post=217147"},{"taxonomy":"post_template","embeddable":true,"href":"https:\/\/urdu.app.com.pk\/urdu\/wp-json\/wp\/v2\/post_template?post=217147"},{"taxonomy":"top_category","embeddable":true,"href":"https:\/\/urdu.app.com.pk\/urdu\/wp-json\/wp\/v2\/top_category?post=217147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}